{"id":2151,"date":"2008-12-05T16:35:25","date_gmt":"2008-12-05T16:35:25","guid":{"rendered":"https:\/\/www.asuntospublicos.cl\/ap\/?p=1352"},"modified":"2021-07-15T04:03:25","modified_gmt":"2021-07-15T04:03:25","slug":"institucionalizacion-del-sistema-de-partidos-enganosa-panacea","status":"publish","type":"post","link":"https:\/\/www.asuntospublicos.cl\/ap\/institucionalizacion-del-sistema-de-partidos-enganosa-panacea\/","title":{"rendered":"Institucionalizaci\u00f3n del Sistema de Partidos: Enga\u00f1osa Panacea"},"content":{"rendered":"<p>Por Alexander Mici . . .<\/p>\n<p>Este informe es de acceso restringido. Para descargar el contenido ingresa tu usuario y contrase\u00f1a en la secci\u00f3n \u201c<a href=\"https:\/\/www.asuntospublicos.cl\/ap\/acceso\/\">Acceso<\/a>\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Alexander Mici<\/p>\n","protected":false},"author":1,"featured_media":4149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,6,4],"tags":[],"class_list":["post-2151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-descargas","category-informes-anteriores","category-politica"],"_links":{"self":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts\/2151"}],"collection":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/comments?post=2151"}],"version-history":[{"count":2,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts\/2151\/revisions"}],"predecessor-version":[{"id":12407,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts\/2151\/revisions\/12407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/media\/4149"}],"wp:attachment":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/media?parent=2151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/categories?post=2151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/tags?post=2151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}