{"id":2012,"date":"2009-08-10T18:21:20","date_gmt":"2009-08-10T18:21:20","guid":{"rendered":"https:\/\/www.asuntospublicos.cl\/ap\/?p=4011"},"modified":"2021-07-15T02:11:27","modified_gmt":"2021-07-15T02:11:27","slug":"la-formacion-del-estado-de-bienestar","status":"publish","type":"post","link":"https:\/\/www.asuntospublicos.cl\/ap\/la-formacion-del-estado-de-bienestar\/","title":{"rendered":"La formaci\u00f3n del Estado de Bienestar"},"content":{"rendered":"<p>Por Paula Z\u00fa\u00f1iga Calder\u00f3n . . .<\/p>\n<p>Este informe es de acceso restringido. Para descargar el contenido ingresa tu usuario y contrase\u00f1a en la secci\u00f3n \u201c<a href=\"https:\/\/www.asuntospublicos.cl\/ap\/acceso\/\">Acceso<\/a>\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Paula Z\u00fa\u00f1iga Calder\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":4149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,6,4],"tags":[],"class_list":["post-2012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-descargas","category-informes-anteriores","category-politica"],"_links":{"self":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts\/2012"}],"collection":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/comments?post=2012"}],"version-history":[{"count":2,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts\/2012\/revisions"}],"predecessor-version":[{"id":12346,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts\/2012\/revisions\/12346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/media\/4149"}],"wp:attachment":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/media?parent=2012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/categories?post=2012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/tags?post=2012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}