{"id":1995,"date":"2009-09-22T13:15:07","date_gmt":"2009-09-22T13:15:07","guid":{"rendered":"https:\/\/www.asuntospublicos.cl\/ap\/?p=4115"},"modified":"2021-07-15T02:04:59","modified_gmt":"2021-07-15T02:04:59","slug":"pinera-presidente-una-coyuntura-favorable-para-la-concertacion","status":"publish","type":"post","link":"https:\/\/www.asuntospublicos.cl\/ap\/pinera-presidente-una-coyuntura-favorable-para-la-concertacion\/","title":{"rendered":"\u00a1Pi\u00f1era Presidente! Una coyuntura favorable para la Concertaci\u00f3n"},"content":{"rendered":"<p>Por Crist\u00f3bal Rovira Kaltwasser . . .<\/p>\n<p>Este informe es de acceso restringido. Para descargar el contenido ingresa tu usuario y contrase\u00f1a en la secci\u00f3n \u201c<a href=\"https:\/\/www.asuntospublicos.cl\/ap\/acceso\/\">Acceso<\/a>\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Crist\u00f3bal Rovira Kaltwasser<\/p>\n","protected":false},"author":1,"featured_media":4149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,6,4],"tags":[],"class_list":["post-1995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-descargas","category-informes-anteriores","category-politica"],"_links":{"self":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts\/1995"}],"collection":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/comments?post=1995"}],"version-history":[{"count":2,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts\/1995\/revisions"}],"predecessor-version":[{"id":12334,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/posts\/1995\/revisions\/12334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/media\/4149"}],"wp:attachment":[{"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/media?parent=1995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/categories?post=1995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asuntospublicos.cl\/ap\/wp-json\/wp\/v2\/tags?post=1995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}